{"id":47647,"date":"2024-06-17T19:02:23","date_gmt":"2024-06-17T17:02:23","guid":{"rendered":"https:\/\/inorope.com\/uncategorized\/structural-cables-umbilicals\/"},"modified":"2024-06-17T19:03:02","modified_gmt":"2024-06-17T17:03:02","slug":"structural-cables-umbilicals","status":"publish","type":"post","link":"https:\/\/inorope.com\/en\/ino-rope-solutions\/structural-cables-umbilicals\/","title":{"rendered":"Structural Cables \u2013 Umbilicals"},"content":{"rendered":"<style>.kb-row-layout-id47225_3e7dc0-24 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id47225_3e7dc0-24 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id47225_3e7dc0-24 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1290px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:var(--global-kb-spacing-xxl, 5rem);padding-bottom:var(--global-kb-spacing-xxl, 5rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id47225_3e7dc0-24{background-color:#f7f8f8;}.kb-row-layout-id47225_3e7dc0-24 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id47225_3e7dc0-24 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id47225_3e7dc0-24 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id47225_3e7dc0-24 alignnone kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column47225_c4616c-c2 > .kt-inside-inner-col,.kadence-column47225_c4616c-c2 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column47225_c4616c-c2 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column47225_c4616c-c2 > .kt-inside-inner-col{flex-direction:column;}.kadence-column47225_c4616c-c2 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column47225_c4616c-c2 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column47225_c4616c-c2{position:relative;}@media all and (max-width: 1024px){.kadence-column47225_c4616c-c2 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column47225_c4616c-c2 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column47225_c4616c-c2\"><div class=\"kt-inside-inner-col\">\n<h1 class=\"wp-block-heading has-text-color has-link-color wp-elements-1\" style=\"color:#4066ff;font-size:60px;font-style:normal;font-weight:800;line-height:1.3\"><strong>Structural Cables \u2013 Umbilicals<\/strong><\/h1>\n<\/div><\/div>\n\n<\/div><\/div><style>.kb-row-layout-id47225_d96636-61 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id47225_d96636-61 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id47225_d96636-61 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-lg, 4rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:50px;padding-right:0px;padding-bottom:50px;padding-left:0px;grid-template-columns:minmax(0, calc(15% - ((var(--global-kb-gap-lg, 4rem) * 1 )\/2)))minmax(0, calc(85% - ((var(--global-kb-gap-lg, 4rem) * 1 )\/2)));}.kb-row-layout-id47225_d96636-61{background-color:#f7f8f8;}.kb-row-layout-id47225_d96636-61 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id47225_d96636-61 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr) minmax(0, 2fr);}}@media all and (max-width: 767px){.kb-row-layout-id47225_d96636-61 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id47225_d96636-61 alignnone kt-row-has-bg custom-col wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-right-golden kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column47225_98ced7-78 > .kt-inside-inner-col,.kadence-column47225_98ced7-78 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column47225_98ced7-78 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column47225_98ced7-78 > .kt-inside-inner-col{flex-direction:column;}.kadence-column47225_98ced7-78 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column47225_98ced7-78 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column47225_98ced7-78{position:relative;}@media all and (max-width: 1024px){.kadence-column47225_98ced7-78 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column47225_98ced7-78 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column47225_98ced7-78\"><div class=\"kt-inside-inner-col\"><\/div><\/div>\n\n\n<style>.kadence-column47225_b0f2a0-ed > .kt-inside-inner-col,.kadence-column47225_b0f2a0-ed > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column47225_b0f2a0-ed > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column47225_b0f2a0-ed > .kt-inside-inner-col{flex-direction:column;}.kadence-column47225_b0f2a0-ed > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column47225_b0f2a0-ed > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column47225_b0f2a0-ed{position:relative;}@media all and (max-width: 1024px){.kadence-column47225_b0f2a0-ed > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column47225_b0f2a0-ed > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column47225_b0f2a0-ed\"><div class=\"kt-inside-inner-col\"><div class=\"wp-block-image\">\n<figure class=\"alignright size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/inorope.com\/wp-content\/uploads\/2024\/05\/cable-ombilical-Ino-Rope-web.png\" alt=\"\" class=\"wp-image-47226\" style=\"aspect-ratio:16\/9;object-fit:cover\"\/><\/figure>\n<\/div><\/div><\/div>\n\n<\/div><\/div><style>.kb-row-layout-id47225_819dd7-21 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id47225_819dd7-21 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id47225_819dd7-21 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-lg, 4rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1290px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:50px;padding-bottom:50px;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id47225_819dd7-21{background-color:#f7f8f8;}.kb-row-layout-id47225_819dd7-21 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id47225_819dd7-21 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id47225_819dd7-21 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id47225_819dd7-21 alignnone kt-row-has-bg custom-col wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column47225_5f1917-b3 > .kt-inside-inner-col,.kadence-column47225_5f1917-b3 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column47225_5f1917-b3 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column47225_5f1917-b3 > .kt-inside-inner-col{flex-direction:column;}.kadence-column47225_5f1917-b3 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column47225_5f1917-b3 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column47225_5f1917-b3{position:relative;}@media all and (max-width: 1024px){.kadence-column47225_5f1917-b3 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column47225_5f1917-b3 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column47225_5f1917-b3\"><div class=\"kt-inside-inner-col\">\n<h2 class=\"wp-block-heading has-text-color has-link-color wp-elements-2\" style=\"color:#4066ff;font-size:60px;line-height:1\"><strong>Custom Designed&#13;\n<\/strong><\/h2>\n<\/div><\/div>\n\n<\/div><\/div><style>.kb-row-layout-id47225_ba2086-21 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id47225_ba2086-21 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id47225_ba2086-21 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-lg, 4rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1290px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:50px;padding-bottom:50px;grid-template-columns:repeat(2, minmax(0, 1fr));}.kb-row-layout-id47225_ba2086-21{background-image:linear-gradient(180deg,rgb(247,248,248) 0%,var(--global-palette9,#ffffff) 50%);}.kb-row-layout-id47225_ba2086-21 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id47225_ba2086-21 > .kt-row-column-wrap{grid-template-columns:repeat(2, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id47225_ba2086-21 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id47225_ba2086-21 alignnone kt-row-has-bg custom-col wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column47225_f1f1e3-83 > .kt-inside-inner-col,.kadence-column47225_f1f1e3-83 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column47225_f1f1e3-83 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column47225_f1f1e3-83 > .kt-inside-inner-col{flex-direction:column;}.kadence-column47225_f1f1e3-83 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column47225_f1f1e3-83 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column47225_f1f1e3-83{position:relative;}@media all and (max-width: 1024px){.kadence-column47225_f1f1e3-83 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column47225_f1f1e3-83 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column47225_f1f1e3-83\"><div class=\"kt-inside-inner-col\">\n<p class=\"wp-block-paragraph\" style=\"padding-right:30px;font-size:20px\"><strong>Our expertise lies in creating products and solutions using high-performance textile fibers. We specialize in the design of structural umbilical cables, tailored to meet the requirements of your specifications. Thanks to exceptional mechanical strength, our cables are perfectly suited for a variety of applications, including transporting electrical current, data via optical fiber, or fluids.<\/strong><\/p>\n<\/div><\/div>\n\n\n<style>.kadence-column47225_224e18-ca > .kt-inside-inner-col,.kadence-column47225_224e18-ca > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column47225_224e18-ca > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column47225_224e18-ca > .kt-inside-inner-col{flex-direction:column;}.kadence-column47225_224e18-ca > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column47225_224e18-ca > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column47225_224e18-ca{position:relative;}@media all and (max-width: 1024px){.kadence-column47225_224e18-ca > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column47225_224e18-ca > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column47225_224e18-ca\"><div class=\"kt-inside-inner-col\"><\/div><\/div>\n\n<\/div><\/div><style>.kb-row-layout-id47225_03955b-bb > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id47225_03955b-bb > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id47225_03955b-bb > .kt-row-column-wrap{column-gap:var(--global-kb-gap-lg, 4rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1290px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:var(--global-kb-spacing-xl, 4rem);padding-bottom:var(--global-kb-spacing-xl, 4rem);grid-template-columns:repeat(2, minmax(0, 1fr));}.kb-row-layout-id47225_03955b-bb > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id47225_03955b-bb > .kt-row-column-wrap{grid-template-columns:repeat(2, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id47225_03955b-bb > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id47225_03955b-bb alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column47225_ba2f8c-21 > .kt-inside-inner-col,.kadence-column47225_ba2f8c-21 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column47225_ba2f8c-21 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column47225_ba2f8c-21 > .kt-inside-inner-col{flex-direction:column;}.kadence-column47225_ba2f8c-21 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column47225_ba2f8c-21 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column47225_ba2f8c-21{position:relative;}@media all and (max-width: 1024px){.kadence-column47225_ba2f8c-21 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column47225_ba2f8c-21 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column47225_ba2f8c-21\"><div class=\"kt-inside-inner-col\">\n<h2 class=\"wp-block-heading news-title-custom has-theme-palette-2-color has-text-color has-link-color wp-elements-3\" style=\"padding-bottom:50px;font-size:24px;line-height:1\"><strong>High Strength<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"font-size:20px\">Each layer of our cables is meticulously designed to ensure optimal mechanical, electrical, and thermal properties, perfectly tailored to your specific needs. Their very high strength allows for both static and dynamic use, even in extreme conditions such as mounting with pulleys or winches.<\/p>\n<\/div><\/div>\n\n\n<style>.kadence-column47225_f70f74-da > .kt-inside-inner-col,.kadence-column47225_f70f74-da > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column47225_f70f74-da > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column47225_f70f74-da > .kt-inside-inner-col{flex-direction:column;}.kadence-column47225_f70f74-da > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column47225_f70f74-da > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column47225_f70f74-da{position:relative;}@media all and (max-width: 1024px){.kadence-column47225_f70f74-da > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column47225_f70f74-da > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column47225_f70f74-da\"><div class=\"kt-inside-inner-col\">\n<h2 class=\"wp-block-heading news-title-custom has-theme-palette-2-color has-text-color has-link-color wp-elements-4\" style=\"padding-bottom:50px;font-size:24px;line-height:1\"><strong>Performance and Reliability<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"font-size:20px\">Choose performance and reliability with our Structural Cables \u2013 Umbilicals, a custom solution designed to meet all your technical challenges.<\/p>\n<\/div><\/div>\n\n<\/div><\/div><style>.kb-row-layout-id46484_0e2776-8d > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id46484_0e2776-8d > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id46484_0e2776-8d > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1290px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:0px;padding-bottom:var(--global-kb-spacing-xl, 4rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id46484_0e2776-8d > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id46484_0e2776-8d > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id46484_0e2776-8d > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id46484_0e2776-8d alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column46484_6cc74b-1e > .kt-inside-inner-col,.kadence-column46484_6cc74b-1e > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column46484_6cc74b-1e > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column46484_6cc74b-1e > .kt-inside-inner-col{flex-direction:column;}.kadence-column46484_6cc74b-1e > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column46484_6cc74b-1e > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column46484_6cc74b-1e{position:relative;}@media all and (max-width: 1024px){.kadence-column46484_6cc74b-1e > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column46484_6cc74b-1e > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column46484_6cc74b-1e\"><div class=\"kt-inside-inner-col\"><style>.kb-row-layout-id46484_957aea-7f > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id46484_957aea-7f > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id46484_957aea-7f > .kt-row-column-wrap{column-gap:var(--global-kb-gap-lg, 4rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1290px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:64px;padding-right:50px;padding-bottom:180px;padding-left:50px;grid-template-columns:minmax(0, calc(45% - ((var(--global-kb-gap-lg, 4rem) * 1 )\/2)))minmax(0, calc(55% - ((var(--global-kb-gap-lg, 4rem) * 1 )\/2)));}.kb-row-layout-id46484_957aea-7f{background-color:#f7f8f8;}.kb-row-layout-id46484_957aea-7f > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id46484_957aea-7f > .kt-row-column-wrap{grid-template-columns:repeat(2, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id46484_957aea-7f > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id46484_957aea-7f alignnone kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column46484_dda42e-7a > .kt-inside-inner-col,.kadence-column46484_dda42e-7a > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column46484_dda42e-7a > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column46484_dda42e-7a > .kt-inside-inner-col{flex-direction:column;}.kadence-column46484_dda42e-7a > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column46484_dda42e-7a > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column46484_dda42e-7a{position:relative;}@media all and (max-width: 1024px){.kadence-column46484_dda42e-7a > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column46484_dda42e-7a > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column46484_dda42e-7a\"><div class=\"kt-inside-inner-col\">\n<h2 class=\"wp-block-heading has-theme-palette-2-color has-text-color has-link-color wp-elements-5\" style=\"font-size:60px;font-style:normal;font-weight:800;line-height:1\"><strong>A Specific<br\/>Need ?<\/strong><\/h2>\n<\/div><\/div>\n\n\n<style>.kadence-column46484_0b3804-5b > .kt-inside-inner-col,.kadence-column46484_0b3804-5b > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column46484_0b3804-5b > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column46484_0b3804-5b > .kt-inside-inner-col{flex-direction:column;}.kadence-column46484_0b3804-5b > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column46484_0b3804-5b > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column46484_0b3804-5b{position:relative;}@media all and (max-width: 1024px){.kadence-column46484_0b3804-5b > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column46484_0b3804-5b > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column46484_0b3804-5b\"><div class=\"kt-inside-inner-col\">\n<p class=\"has-theme-palette-1-color has-text-color has-link-color wp-elements-6 wp-block-paragraph\" style=\"font-size:18px\"><strong>INO-ROPE is committed to providing innovative and high-quality rope-based solutions, supported by unparalleled expertise and dedication to customer satisfaction.<\/strong><\/p>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id46484_8bdbc8-fb{margin-top:-120px;}.kb-row-layout-id46484_8bdbc8-fb > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id46484_8bdbc8-fb > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id46484_8bdbc8-fb > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:60%;margin-left:auto;margin-right:auto;padding-top:0px;padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id46484_8bdbc8-fb > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id46484_8bdbc8-fb > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id46484_8bdbc8-fb > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id46484_8bdbc8-fb alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column46484_4a1214-b1 > .kt-inside-inner-col{padding-top:0px;}.kadence-column46484_4a1214-b1 > .kt-inside-inner-col,.kadence-column46484_4a1214-b1 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column46484_4a1214-b1 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column46484_4a1214-b1 > .kt-inside-inner-col{flex-direction:column;}.kadence-column46484_4a1214-b1 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column46484_4a1214-b1 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column46484_4a1214-b1{position:relative;}@media all and (max-width: 1024px){.kadence-column46484_4a1214-b1 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column46484_4a1214-b1 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column46484_4a1214-b1\"><div class=\"kt-inside-inner-col\"><style>.kb-row-layout-id46484_54c061-3b > .kt-row-column-wrap{align-content:center;}:where(.kb-row-layout-id46484_54c061-3b > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:center;}.kb-row-layout-id46484_54c061-3b > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:var(--global-kb-spacing-lg, 3rem);padding-right:var(--global-kb-spacing-lg, 3rem);padding-bottom:var(--global-kb-spacing-lg, 3rem);padding-left:var(--global-kb-spacing-lg, 3rem);grid-template-columns:minmax(0, 2fr) minmax(0, 1fr);}.kb-row-layout-id46484_54c061-3b{background-color:#4066ff;}.kb-row-layout-id46484_54c061-3b > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id46484_54c061-3b > .kt-row-column-wrap{grid-template-columns:minmax(0, 2fr) minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id46484_54c061-3b > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id46484_54c061-3b alignnone kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-left-golden kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-middle\">\n<style>.kadence-column46484_b4d729-91 > .kt-inside-inner-col,.kadence-column46484_b4d729-91 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column46484_b4d729-91 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column46484_b4d729-91 > .kt-inside-inner-col{flex-direction:column;}.kadence-column46484_b4d729-91 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column46484_b4d729-91 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column46484_b4d729-91{position:relative;}@media all and (max-width: 1024px){.kadence-column46484_b4d729-91 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column46484_b4d729-91 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column46484_b4d729-91\"><div class=\"kt-inside-inner-col\">\n<p class=\"has-theme-palette-9-color has-text-color has-link-color wp-elements-7 wp-block-paragraph\">Contact us to discover how we can help you achieve your most ambitious projects.<\/p>\n<\/div><\/div>\n\n\n<style>.kadence-column46484_3adad1-f3 > .kt-inside-inner-col,.kadence-column46484_3adad1-f3 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column46484_3adad1-f3 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column46484_3adad1-f3 > .kt-inside-inner-col{flex-direction:column;}.kadence-column46484_3adad1-f3 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column46484_3adad1-f3 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column46484_3adad1-f3{position:relative;}@media all and (max-width: 1024px){.kadence-column46484_3adad1-f3 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column46484_3adad1-f3 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column46484_3adad1-f3\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedbtn.kb-btns46484_c71bdd-46{gap:var(--global-kb-gap-xs, 0.5rem );justify-content:center;align-items:center;}.kt-btns46484_c71bdd-46 .kt-button{font-weight:normal;font-style:normal;}.kt-btns46484_c71bdd-46 .kt-btn-wrap-0{margin-right:5px;}.wp-block-kadence-advancedbtn.kt-btns46484_c71bdd-46 .kt-btn-wrap-0 .kt-button{color:#555555;border-color:#555555;}.wp-block-kadence-advancedbtn.kt-btns46484_c71bdd-46 .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns46484_c71bdd-46 .kt-btn-wrap-0 .kt-button:focus{color:#ffffff;border-color:#444444;}.wp-block-kadence-advancedbtn.kt-btns46484_c71bdd-46 .kt-btn-wrap-0 .kt-button::before{display:none;}.wp-block-kadence-advancedbtn.kt-btns46484_c71bdd-46 .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns46484_c71bdd-46 .kt-btn-wrap-0 .kt-button:focus{background:#444444;}<\/style>\n<div class=\"wp-block-kadence-advancedbtn kb-buttons-wrap kb-btns46484_c71bdd-46\"><style>.wp-block-kadence-advancedbtn .kb-btn46484_b37877-45.kb-button, ul.menu .wp-block-kadence-advancedbtn .kb-btn46484_b37877-45.kb-button{width:116px;}.wp-block-kadence-advancedbtn .kb-btn46484_b37877-45.kb-button{color:#4066ff;background:var(--global-palette9, #ffffff);border-top-left-radius:10px;border-top-right-radius:10px;border-bottom-right-radius:10px;border-bottom-left-radius:10px;padding-top:15px;padding-bottom:15px;}<\/style><a class=\"kb-button kt-button button kb-btn46484_b37877-45 kt-btn-size-standard kt-btn-width-type-fixed kb-btn-global-fill kt-btn-has-text-true kt-btn-has-svg-false wp-block-kadence-singlebtn\" href=\"https:\/\/inorope.com\/en\/contact\/\"><span class=\"kt-btn-inner-text\"><strong>Go !<\/strong><\/span><\/a><\/div>\n<\/div><\/div>\n\n<\/div><\/div><\/div><\/div>\n\n<\/div><\/div><\/div><\/div>\n\n<\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Structural Cables \u2013 Umbilicals Custom Designed&#13; Our expertise lies in creating products and solutions using high-performance textile fibers. We specialize in the design of structural umbilical cables, tailored to meet the requirements of your specifications. Thanks to exceptional mechanical strength, our cables are perfectly suited for a variety of applications, including transporting electrical current, data&#8230;<\/p>\n","protected":false},"author":1,"featured_media":47227,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","_kad_post_transparent":"disable","_kad_post_title":"hide","_kad_post_layout":"fullwidth","_kad_post_sidebar_id":"","_kad_post_content_style":"unboxed","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","footnotes":""},"categories":[89],"tags":[101,96,92],"class_list":["post-47647","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ino-rope-solutions","tag-boating","tag-defense-en","tag-marine-renewable-energies"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Structural Cables \u2013 Umbilicals - Ino-Rope<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/inorope.com\/en\/ino-rope-solutions\/structural-cables-umbilicals\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Structural Cables \u2013 Umbilicals - Ino-Rope\" \/>\n<meta property=\"og:description\" content=\"Structural Cables \u2013 Umbilicals Custom Designed&#013; Our expertise lies in creating products and solutions using high-performance textile fibers. We specialize in the design of structural umbilical cables, tailored to meet the requirements of your specifications. Thanks to exceptional mechanical strength, our cables are perfectly suited for a variety of applications, including transporting electrical current, data...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/inorope.com\/en\/ino-rope-solutions\/structural-cables-umbilicals\/\" \/>\n<meta property=\"og:site_name\" content=\"Ino-Rope\" \/>\n<meta property=\"article:published_time\" content=\"2024-06-17T17:02:23+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-06-17T17:03:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/inorope.com\/wp-content\/uploads\/2024\/05\/cable-ombilical-Ino-Rope-web.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"La_palm_de_l_incompetence\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"La_palm_de_l_incompetence\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/inorope.com\\\/en\\\/ino-rope-solutions\\\/structural-cables-umbilicals\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/inorope.com\\\/en\\\/ino-rope-solutions\\\/structural-cables-umbilicals\\\/\"},\"author\":{\"name\":\"La_palm_de_l_incompetence\",\"@id\":\"https:\\\/\\\/inorope.com\\\/#\\\/schema\\\/person\\\/fe3b16d660afeaa98ee1e67cb2590db5\"},\"headline\":\"Structural Cables \u2013 Umbilicals\",\"datePublished\":\"2024-06-17T17:02:23+00:00\",\"dateModified\":\"2024-06-17T17:03:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/inorope.com\\\/en\\\/ino-rope-solutions\\\/structural-cables-umbilicals\\\/\"},\"wordCount\":130,\"publisher\":{\"@id\":\"https:\\\/\\\/inorope.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/inorope.com\\\/en\\\/ino-rope-solutions\\\/structural-cables-umbilicals\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/inorope.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cable-ombilical-Ino-Rope-web.png\",\"keywords\":[\"Boating\",\"Defense\",\"Marine Renewable Energies\"],\"articleSection\":[\"Ino-Rope solutions\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/inorope.com\\\/en\\\/ino-rope-solutions\\\/structural-cables-umbilicals\\\/\",\"url\":\"https:\\\/\\\/inorope.com\\\/en\\\/ino-rope-solutions\\\/structural-cables-umbilicals\\\/\",\"name\":\"Structural Cables \u2013 Umbilicals - Ino-Rope\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/inorope.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/inorope.com\\\/en\\\/ino-rope-solutions\\\/structural-cables-umbilicals\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/inorope.com\\\/en\\\/ino-rope-solutions\\\/structural-cables-umbilicals\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/inorope.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cable-ombilical-Ino-Rope-web.png\",\"datePublished\":\"2024-06-17T17:02:23+00:00\",\"dateModified\":\"2024-06-17T17:03:02+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/inorope.com\\\/en\\\/ino-rope-solutions\\\/structural-cables-umbilicals\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/inorope.com\\\/en\\\/ino-rope-solutions\\\/structural-cables-umbilicals\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/inorope.com\\\/en\\\/ino-rope-solutions\\\/structural-cables-umbilicals\\\/#primaryimage\",\"url\":\"https:\\\/\\\/inorope.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cable-ombilical-Ino-Rope-web.png\",\"contentUrl\":\"https:\\\/\\\/inorope.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cable-ombilical-Ino-Rope-web.png\",\"width\":800,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/inorope.com\\\/en\\\/ino-rope-solutions\\\/structural-cables-umbilicals\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/inorope.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ino-Rope solutions\",\"item\":\"https:\\\/\\\/inorope.com\\\/en\\\/category\\\/ino-rope-solutions\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Structural Cables \u2013 Umbilicals\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/inorope.com\\\/#website\",\"url\":\"https:\\\/\\\/inorope.com\\\/\",\"name\":\"Ino-Rope\",\"description\":\"La fibre High-Tech au service de nos innovations\",\"publisher\":{\"@id\":\"https:\\\/\\\/inorope.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/inorope.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/inorope.com\\\/#organization\",\"name\":\"Ino-Rope\",\"url\":\"https:\\\/\\\/inorope.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/inorope.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/inorope.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/INOROPE-logo.png\",\"contentUrl\":\"https:\\\/\\\/inorope.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/INOROPE-logo.png\",\"width\":191,\"height\":35,\"caption\":\"Ino-Rope\"},\"image\":{\"@id\":\"https:\\\/\\\/inorope.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/inorope.com\\\/#\\\/schema\\\/person\\\/fe3b16d660afeaa98ee1e67cb2590db5\",\"name\":\"La_palm_de_l_incompetence\",\"url\":\"https:\\\/\\\/inorope.com\\\/en\\\/author\\\/la_palm_de_l_incompetence\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Structural Cables \u2013 Umbilicals - Ino-Rope","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/inorope.com\/en\/ino-rope-solutions\/structural-cables-umbilicals\/","og_locale":"en_US","og_type":"article","og_title":"Structural Cables \u2013 Umbilicals - Ino-Rope","og_description":"Structural Cables \u2013 Umbilicals Custom Designed&#13; Our expertise lies in creating products and solutions using high-performance textile fibers. We specialize in the design of structural umbilical cables, tailored to meet the requirements of your specifications. Thanks to exceptional mechanical strength, our cables are perfectly suited for a variety of applications, including transporting electrical current, data...","og_url":"https:\/\/inorope.com\/en\/ino-rope-solutions\/structural-cables-umbilicals\/","og_site_name":"Ino-Rope","article_published_time":"2024-06-17T17:02:23+00:00","article_modified_time":"2024-06-17T17:03:02+00:00","og_image":[{"width":800,"height":800,"url":"https:\/\/inorope.com\/wp-content\/uploads\/2024\/05\/cable-ombilical-Ino-Rope-web.png","type":"image\/png"}],"author":"La_palm_de_l_incompetence","twitter_card":"summary_large_image","twitter_misc":{"Written by":"La_palm_de_l_incompetence","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/inorope.com\/en\/ino-rope-solutions\/structural-cables-umbilicals\/#article","isPartOf":{"@id":"https:\/\/inorope.com\/en\/ino-rope-solutions\/structural-cables-umbilicals\/"},"author":{"name":"La_palm_de_l_incompetence","@id":"https:\/\/inorope.com\/#\/schema\/person\/fe3b16d660afeaa98ee1e67cb2590db5"},"headline":"Structural Cables \u2013 Umbilicals","datePublished":"2024-06-17T17:02:23+00:00","dateModified":"2024-06-17T17:03:02+00:00","mainEntityOfPage":{"@id":"https:\/\/inorope.com\/en\/ino-rope-solutions\/structural-cables-umbilicals\/"},"wordCount":130,"publisher":{"@id":"https:\/\/inorope.com\/#organization"},"image":{"@id":"https:\/\/inorope.com\/en\/ino-rope-solutions\/structural-cables-umbilicals\/#primaryimage"},"thumbnailUrl":"https:\/\/inorope.com\/wp-content\/uploads\/2024\/05\/cable-ombilical-Ino-Rope-web.png","keywords":["Boating","Defense","Marine Renewable Energies"],"articleSection":["Ino-Rope solutions"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/inorope.com\/en\/ino-rope-solutions\/structural-cables-umbilicals\/","url":"https:\/\/inorope.com\/en\/ino-rope-solutions\/structural-cables-umbilicals\/","name":"Structural Cables \u2013 Umbilicals - Ino-Rope","isPartOf":{"@id":"https:\/\/inorope.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/inorope.com\/en\/ino-rope-solutions\/structural-cables-umbilicals\/#primaryimage"},"image":{"@id":"https:\/\/inorope.com\/en\/ino-rope-solutions\/structural-cables-umbilicals\/#primaryimage"},"thumbnailUrl":"https:\/\/inorope.com\/wp-content\/uploads\/2024\/05\/cable-ombilical-Ino-Rope-web.png","datePublished":"2024-06-17T17:02:23+00:00","dateModified":"2024-06-17T17:03:02+00:00","breadcrumb":{"@id":"https:\/\/inorope.com\/en\/ino-rope-solutions\/structural-cables-umbilicals\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/inorope.com\/en\/ino-rope-solutions\/structural-cables-umbilicals\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/inorope.com\/en\/ino-rope-solutions\/structural-cables-umbilicals\/#primaryimage","url":"https:\/\/inorope.com\/wp-content\/uploads\/2024\/05\/cable-ombilical-Ino-Rope-web.png","contentUrl":"https:\/\/inorope.com\/wp-content\/uploads\/2024\/05\/cable-ombilical-Ino-Rope-web.png","width":800,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/inorope.com\/en\/ino-rope-solutions\/structural-cables-umbilicals\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/inorope.com\/en\/"},{"@type":"ListItem","position":2,"name":"Ino-Rope solutions","item":"https:\/\/inorope.com\/en\/category\/ino-rope-solutions\/"},{"@type":"ListItem","position":3,"name":"Structural Cables \u2013 Umbilicals"}]},{"@type":"WebSite","@id":"https:\/\/inorope.com\/#website","url":"https:\/\/inorope.com\/","name":"Ino-Rope","description":"La fibre High-Tech au service de nos innovations","publisher":{"@id":"https:\/\/inorope.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/inorope.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/inorope.com\/#organization","name":"Ino-Rope","url":"https:\/\/inorope.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/inorope.com\/#\/schema\/logo\/image\/","url":"https:\/\/inorope.com\/wp-content\/uploads\/2024\/03\/INOROPE-logo.png","contentUrl":"https:\/\/inorope.com\/wp-content\/uploads\/2024\/03\/INOROPE-logo.png","width":191,"height":35,"caption":"Ino-Rope"},"image":{"@id":"https:\/\/inorope.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/inorope.com\/#\/schema\/person\/fe3b16d660afeaa98ee1e67cb2590db5","name":"La_palm_de_l_incompetence","url":"https:\/\/inorope.com\/en\/author\/la_palm_de_l_incompetence\/"}]}},"taxonomy_info":{"category":[{"value":89,"label":"Ino-Rope solutions"}],"post_tag":[{"value":101,"label":"Boating"},{"value":96,"label":"Defense"},{"value":92,"label":"Marine Renewable Energies"}]},"featured_image_src_large":["https:\/\/inorope.com\/wp-content\/uploads\/2024\/05\/cable-ombilical-Ino-Rope-web.png",800,800,false],"author_info":{"display_name":"La_palm_de_l_incompetence","author_link":"https:\/\/inorope.com\/en\/author\/la_palm_de_l_incompetence\/"},"comment_info":0,"category_info":[{"term_id":89,"name":"Ino-Rope solutions","slug":"ino-rope-solutions","term_group":0,"term_taxonomy_id":89,"taxonomy":"category","description":"","parent":0,"count":10,"filter":"raw","term_order":"0","cat_ID":89,"category_count":10,"category_description":"","cat_name":"Ino-Rope solutions","category_nicename":"ino-rope-solutions","category_parent":0}],"tag_info":[{"term_id":101,"name":"Boating","slug":"boating","term_group":0,"term_taxonomy_id":101,"taxonomy":"post_tag","description":"","parent":0,"count":5,"filter":"raw","term_order":"0"},{"term_id":96,"name":"Defense","slug":"defense-en","term_group":0,"term_taxonomy_id":96,"taxonomy":"post_tag","description":"","parent":0,"count":4,"filter":"raw","term_order":"0"},{"term_id":92,"name":"Marine Renewable Energies","slug":"marine-renewable-energies","term_group":0,"term_taxonomy_id":92,"taxonomy":"post_tag","description":"","parent":0,"count":4,"filter":"raw","term_order":"0"}],"_links":{"self":[{"href":"https:\/\/inorope.com\/en\/wp-json\/wp\/v2\/posts\/47647","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/inorope.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/inorope.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/inorope.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/inorope.com\/en\/wp-json\/wp\/v2\/comments?post=47647"}],"version-history":[{"count":2,"href":"https:\/\/inorope.com\/en\/wp-json\/wp\/v2\/posts\/47647\/revisions"}],"predecessor-version":[{"id":47649,"href":"https:\/\/inorope.com\/en\/wp-json\/wp\/v2\/posts\/47647\/revisions\/47649"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/inorope.com\/en\/wp-json\/wp\/v2\/media\/47227"}],"wp:attachment":[{"href":"https:\/\/inorope.com\/en\/wp-json\/wp\/v2\/media?parent=47647"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/inorope.com\/en\/wp-json\/wp\/v2\/categories?post=47647"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/inorope.com\/en\/wp-json\/wp\/v2\/tags?post=47647"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}